{"id":3201,"date":"2024-07-16T12:26:51","date_gmt":"2024-07-16T12:26:51","guid":{"rendered":"https:\/\/integriscomposites.com\/nachrichten\/"},"modified":"2024-08-07T11:39:52","modified_gmt":"2024-08-07T11:39:52","slug":"nachrichten","status":"publish","type":"page","link":"https:\/\/integriscomposites.com\/de\/nachrichten\/","title":{"rendered":"Nachrichten"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.25.2&#8243; _module_preset=&#8220;default&#8220; background_image=&#8220;https:\/\/integriscomposites.com\/wp-content\/uploads\/2024\/07\/TEN-Signage-Mockup-Revised.jpg&#8220; custom_padding=&#8220;10%||3%||false|false&#8220; bottom_divider_height=&#8220;40px&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row module_class=&#8220;hero-row&#8220; _builder_version=&#8220;4.25.2&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;rgba(0,40,102,0.85)&#8220; width=&#8220;100%&#8220; max_width=&#8220;100%&#8220; custom_padding=&#8220;25px|25px|25px|25px|true|true&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.25.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.25.2&#8243; _module_preset=&#8220;default&#8220; text_text_color=&#8220;#FFFFFF&#8220; header_text_color=&#8220;#FFFFFF&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h1>Nachrichten<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; admin_label=&#8220;section&#8220; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_row admin_label=&#8220;Zeile&#8220; _builder_version=&#8220;4.16&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_blog fullwidth=&#8220;off&#8220; posts_number=&#8220;50&#8243; include_categories=&#8220;all&#8220; excerpt_length=&#8220;120&#8243; show_more=&#8220;on&#8220; show_author=&#8220;off&#8220; show_categories=&#8220;off&#8220; module_class=&#8220;pa-blog-equal-height&#8220; _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; header_level=&#8220;h3&#8243; header_font_size=&#8220;20px&#8220; header_line_height=&#8220;1.1em&#8220; body_font_size=&#8220;16px&#8220; body_line_height=&#8220;1.3em&#8220; read_more_font=&#8220;|||on|||||&#8220; read_more_text_color=&#8220;#FFFFFF&#8220; read_more_font_size=&#8220;16px&#8220; hover_enabled=&#8220;0&#8243; custom_css_free_form=&#8220;selector .et_pb_post .post-content .post-content-inner {||  margin-bottom: 20px !important;||}||.pa-blog-equal-height .pa-auto-height {||    height: auto !important;||}||.pa-blog-equal-height .pa-auto-margin {||    margin-top: 20px !important;||}||.post-content {||    display: flex;||    flex-wrap: wrap;||}&#8220; custom_css_read_more=&#8220;padding: 8px 15px !important;||background-color: #002866;&#8220; border_color_all=&#8220;#002866&#8243; global_colors_info=&#8220;{}&#8220; custom_css_read_more__hover_enabled=&#8220;on|hover&#8220; custom_css_read_more__hover=&#8220;padding: 8px 15px !important;||background-color: #000;&#8220; use_manual_excerpt=&#8220;off&#8220; sticky_enabled=&#8220;0&#8243;][\/et_pb_blog][et_pb_code _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]<script><!-- [et_pb_line_break_holder] -->\t(function ($) {<!-- [et_pb_line_break_holder] -->\t\tvar pa_equalize_button_height = \"true\";<!-- [et_pb_line_break_holder] -->\t\tif (pa_equalize_button_height == \"false\") {<!-- [et_pb_line_break_holder] -->\t\t\tfunction pa_equalize_blog_post_height(blog) {<!-- [et_pb_line_break_holder] -->\t\t\t\tvar articles = blog.find('article');<!-- [et_pb_line_break_holder] -->\t\t\t\tvar heights = [];<!-- [et_pb_line_break_holder] -->\t\t\t\tarticles.each(function () {<!-- [et_pb_line_break_holder] -->\t\t\t\t\tvar height = 0;<!-- [et_pb_line_break_holder] -->\t\t\t\t\theight += ($(this).find('.et_pb_image_container, .et_main_video_container').length != 0) ? $(this).find('.et_pb_image_container, .et_main_video_container').outerHeight(true) : 0;<!-- [et_pb_line_break_holder] -->\t\t\t\t\theight += $(this).find('.entry-title').outerHeight(true);<!-- [et_pb_line_break_holder] -->\t\t\t\t\theight += ($(this).find('.post-meta').length != 0) ? $(this).find('.post-meta').outerHeight(true) : 0;<!-- [et_pb_line_break_holder] -->\t\t\t\t\theight += ($(this).find('.post-content').length != 0) ? $(this).find('.post-content').outerHeight(true) : 0;<!-- [et_pb_line_break_holder] -->\t\t\t\t\theights.push(height);<!-- [et_pb_line_break_holder] -->\t\t\t\t});<!-- [et_pb_line_break_holder] -->\t\t\t\tvar max_height = Math.max.apply(Math, heights);<!-- [et_pb_line_break_holder] -->\t\t\t\tarticles.each(function () {<!-- [et_pb_line_break_holder] -->\t\t\t\t\t$(this).height(max_height);<!-- [et_pb_line_break_holder] -->\t\t\t\t});<!-- [et_pb_line_break_holder] -->\t\t\t}<!-- [et_pb_line_break_holder] -->\t\t} else {<!-- [et_pb_line_break_holder] -->\t\t\tfunction pa_equalize_blog_post_height(blog) {<!-- [et_pb_line_break_holder] -->\t\t\t\tvar articles = blog.find('article');<!-- [et_pb_line_break_holder] -->\t\t\t\tvar heights = [];<!-- [et_pb_line_break_holder] -->\t\t\t\tvar btnheights = [];<!-- [et_pb_line_break_holder] -->\t\t\t\tarticles.each(function () {<!-- [et_pb_line_break_holder] -->\t\t\t\t\tvar height = 0;<!-- [et_pb_line_break_holder] -->\t\t\t\t\tvar btnheight = 0;<!-- [et_pb_line_break_holder] -->\t\t\t\t\tvar basebtnmargin = 20;<!-- [et_pb_line_break_holder] -->\t\t\t\t\theight += ($(this).find('.et_pb_image_container, .et_main_video_container').length != 0) ? $(this).find('.et_pb_image_container, .et_main_video_container').outerHeight(true) : 0;<!-- [et_pb_line_break_holder] -->\t\t\t\t\theight += $(this).find('.entry-title').outerHeight(true);<!-- [et_pb_line_break_holder] -->\t\t\t\t\theight += $(this).find('.post-meta').outerHeight(true);<!-- [et_pb_line_break_holder] -->\t\t\t\t\theight += $(this).find('.post-content').outerHeight(true);<!-- [et_pb_line_break_holder] -->\t\t\t\t\tbtnheight += ($(this).find('.et_pb_image_container, .et_main_video_container').length != 0) ? $(this).find('.et_pb_image_container, .et_main_video_container').outerHeight(true) : 0;<!-- [et_pb_line_break_holder] -->\t\t\t\t\tbtnheight += $(this).find('.entry-title').outerHeight(true);<!-- [et_pb_line_break_holder] -->\t\t\t\t\tbtnheight += $(this).find('.post-meta').outerHeight(true);<!-- [et_pb_line_break_holder] -->\t\t\t\t\tbtnheight += $(this).find(\".post-content p\").outerHeight(true);<!-- [et_pb_line_break_holder] -->\t\t\t\t\tbtnheight += basebtnmargin;<!-- [et_pb_line_break_holder] -->\t\t\t\t\theights.push(height);<!-- [et_pb_line_break_holder] -->\t\t\t\t\tbtnheights.push(btnheight);<!-- [et_pb_line_break_holder] -->\t\t\t\t});<!-- [et_pb_line_break_holder] -->\t\t\t\tvar max_height = Math.max.apply(Math, heights);<!-- [et_pb_line_break_holder] -->\t\t\t\tvar max_btn_height = Math.max.apply(Math, btnheights);<!-- [et_pb_line_break_holder] -->\t\t\t\tarticles.each(function () {<!-- [et_pb_line_break_holder] -->\t\t\t\t\t$(this).height(max_height);<!-- [et_pb_line_break_holder] -->\t\t\t\t\tvar eachheight = 0;<!-- [et_pb_line_break_holder] -->\t\t\t\t\tvar eachbasebtnmargin = 20;<!-- [et_pb_line_break_holder] -->\t\t\t\t\teachheight += ($(this).find('.et_pb_image_container, .et_main_video_container').length != 0) ? $(this).find('.et_pb_image_container, .et_main_video_container').outerHeight(true) : 0;<!-- [et_pb_line_break_holder] -->\t\t\t\t\teachheight += $(this).find('.entry-title').outerHeight(true);<!-- [et_pb_line_break_holder] -->\t\t\t\t\teachheight += $(this).find('.post-meta').outerHeight(true);<!-- [et_pb_line_break_holder] -->\t\t\t\t\teachheight += $(this).find(\".post-content p\").outerHeight(true);<!-- [et_pb_line_break_holder] -->\t\t\t\t\teachheight += eachbasebtnmargin;<!-- [et_pb_line_break_holder] -->\t\t\t\t\tvar requiredbtnmargin = (max_btn_height - eachheight) + eachbasebtnmargin;<!-- [et_pb_line_break_holder] -->\t\t\t\t\t$(this).find(\".more-link\").css(\"margin-top\", requiredbtnmargin + \"px\");<!-- [et_pb_line_break_holder] -->\t\t\t\t});<!-- [et_pb_line_break_holder] -->\t\t\t}<!-- [et_pb_line_break_holder] -->\t\t}<!-- [et_pb_line_break_holder] -->    <!-- [et_pb_line_break_holder] -->\t\t$(document).ready(function () {<!-- [et_pb_line_break_holder] -->\t\t\t$(window).resize(function () {<!-- [et_pb_line_break_holder] -->\t\t\t\tif ($(this).width() >= 768) {<!-- [et_pb_line_break_holder] -->\t\t\t\t\t$(\".pa-blog-equal-height article\").each(function () {<!-- [et_pb_line_break_holder] -->\t\t\t\t\t\t$(this).removeClass(\"pa-auto-height\");<!-- [et_pb_line_break_holder] -->\t\t\t\t\t\t$(this).find(\".more-link\").removeClass(\"pa-auto-margin\");<!-- [et_pb_line_break_holder] -->\t\t\t\t\t})<!-- [et_pb_line_break_holder] -->\t\t\t\t\t$('.pa-blog-equal-height').each(function () {<!-- [et_pb_line_break_holder] -->\t\t\t\t\t\tpa_equalize_blog_post_height($(this));<!-- [et_pb_line_break_holder] -->\t\t\t\t\t});<!-- [et_pb_line_break_holder] -->\t\t\t\t\t$('.pa-blog-equal-height').each(function () {<!-- [et_pb_line_break_holder] -->\t\t\t\t\t\tvar pa_blog = $(this);<!-- [et_pb_line_break_holder] -->\t\t\t\t\t\tpa_equalize_blog_post_height(pa_blog);<!-- [et_pb_line_break_holder] -->\t\t\t\t\t\tvar observer = new MutationObserver(function (mutations) {<!-- [et_pb_line_break_holder] -->\t\t\t\t\t\t\tpa_equalize_blog_post_height(pa_blog);<!-- [et_pb_line_break_holder] -->\t\t\t\t\t\t});<!-- [et_pb_line_break_holder] -->\t\t\t\t\t\tvar config = {<!-- [et_pb_line_break_holder] -->\t\t\t\t\t\t\tsubtree: true,<!-- [et_pb_line_break_holder] -->\t\t\t\t\t\t\tchildList: true<!-- [et_pb_line_break_holder] -->\t\t\t\t\t\t};<!-- [et_pb_line_break_holder] -->\t\t\t\t\t\tobserver.observe(pa_blog[0], config);<!-- [et_pb_line_break_holder] -->\t\t\t\t\t});<!-- [et_pb_line_break_holder] -->\t\t\t\t\t$(document).ajaxComplete(function () {<!-- [et_pb_line_break_holder] -->\t\t\t\t\t\t$('.pa-blog-equal-height').imagesLoaded().then(function () {<!-- [et_pb_line_break_holder] -->\t\t\t\t\t\t\t$('.pa-blog-equal-height').each(function () {<!-- [et_pb_line_break_holder] -->\t\t\t\t\t\t\t\tpa_equalize_blog_post_height($(this));<!-- [et_pb_line_break_holder] -->\t\t\t\t\t\t\t});<!-- [et_pb_line_break_holder] -->\t\t\t\t\t\t});<!-- [et_pb_line_break_holder] -->\t\t\t\t\t});<!-- [et_pb_line_break_holder] -->\t\t\t\t\t$.fn.imagesLoaded = function () {<!-- [et_pb_line_break_holder] -->\t\t\t\t\t\tvar $imgs = this.find('img[src!=\"\"]');<!-- [et_pb_line_break_holder] -->\t\t\t\t\t\tvar dfds = [];<!-- [et_pb_line_break_holder] -->\t\t\t\t\t\tif (!$imgs.length) {<!-- [et_pb_line_break_holder] -->\t\t\t\t\t\t\treturn $.Deferred().resolve().promise();<!-- [et_pb_line_break_holder] -->\t\t\t\t\t\t}<!-- [et_pb_line_break_holder] -->\t\t\t\t\t\t$imgs.each(function () {<!-- [et_pb_line_break_holder] -->\t\t\t\t\t\t\tvar dfd = $.Deferred();<!-- [et_pb_line_break_holder] -->\t\t\t\t\t\t\tdfds.push(dfd);<!-- [et_pb_line_break_holder] -->\t\t\t\t\t\t\tvar img = new Image();<!-- [et_pb_line_break_holder] -->\t\t\t\t\t\t\timg.onload = function () {<!-- [et_pb_line_break_holder] -->\t\t\t\t\t\t\t\tdfd.resolve();<!-- [et_pb_line_break_holder] -->\t\t\t\t\t\t\t};<!-- [et_pb_line_break_holder] -->\t\t\t\t\t\t\timg.onerror = function () {<!-- [et_pb_line_break_holder] -->\t\t\t\t\t\t\t\tdfd.resolve();<!-- [et_pb_line_break_holder] -->\t\t\t\t\t\t\t};<!-- [et_pb_line_break_holder] -->\t\t\t\t\t\t\timg.src = this.src;<!-- [et_pb_line_break_holder] -->\t\t\t\t\t\t});<!-- [et_pb_line_break_holder] -->\t\t\t\t\t\treturn $.when.apply($, dfds);<!-- [et_pb_line_break_holder] -->\t\t\t\t\t}<!-- [et_pb_line_break_holder] -->\t\t\t\t} else {<!-- [et_pb_line_break_holder] -->\t\t\t\t\t$(\".pa-blog-equal-height article\").each(function () {<!-- [et_pb_line_break_holder] -->\t\t\t\t\t\t$(this).addClass(\"pa-auto-height\");<!-- [et_pb_line_break_holder] -->\t\t\t\t\t\t$(this).find(\".more-link\").addClass(\"pa-auto-margin\");<!-- [et_pb_line_break_holder] -->\t\t\t\t\t})<!-- [et_pb_line_break_holder] -->\t\t\t\t}<!-- [et_pb_line_break_holder] -->\t\t\t});<!-- [et_pb_line_break_holder] -->\t\t});<!-- [et_pb_line_break_holder] -->\t})(jQuery); <!-- [et_pb_line_break_holder] --><\/script>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nachrichten<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_monsterinsights_skip_tracking":false,"footnotes":""},"class_list":["post-3201","page","type-page","status-publish","hentry"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Bleiben Sie auf dem Laufenden mit Nachrichten zum ballistischen Schutz aus Europa und den Vereinigten Staaten.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/integriscomposites.com\/de\/nachrichten\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Integris - Global leader in Survivability Engineering &amp; Technical Composites\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Ballistischer Schutz Nachrichten\" \/>\n\t\t<meta property=\"og:description\" content=\"Bleiben Sie auf dem Laufenden mit Nachrichten zum ballistischen Schutz aus Europa und den Vereinigten Staaten.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/integriscomposites.com\/de\/nachrichten\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-07-16T12:26:51+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-08-07T11:39:52+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Ballistischer Schutz Nachrichten\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Bleiben Sie auf dem Laufenden mit Nachrichten zum ballistischen Schutz aus Europa und den Vereinigten Staaten.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/integriscomposites.com\\\/de\\\/nachrichten\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/integriscomposites.com\\\/de\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/integriscomposites.com\\\/de\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/integriscomposites.com\\\/de\\\/nachrichten\\\/#listItem\",\"name\":\"Nachrichten\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/integriscomposites.com\\\/de\\\/nachrichten\\\/#listItem\",\"position\":2,\"name\":\"Nachrichten\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/integriscomposites.com\\\/de\\\/#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/integriscomposites.com\\\/de\\\/#organization\",\"name\":\"Integris\",\"description\":\"Global leader in Survivability Engineering & Technical Composites\",\"url\":\"https:\\\/\\\/integriscomposites.com\\\/de\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/integriscomposites.com\\\/de\\\/nachrichten\\\/#webpage\",\"url\":\"https:\\\/\\\/integriscomposites.com\\\/de\\\/nachrichten\\\/\",\"name\":\"Ballistischer Schutz Nachrichten\",\"description\":\"Bleiben Sie auf dem Laufenden mit Nachrichten zum ballistischen Schutz aus Europa und den Vereinigten Staaten.\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/integriscomposites.com\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/integriscomposites.com\\\/de\\\/nachrichten\\\/#breadcrumblist\"},\"datePublished\":\"2024-07-16T12:26:51+00:00\",\"dateModified\":\"2024-08-07T11:39:52+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/integriscomposites.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/integriscomposites.com\\\/de\\\/\",\"name\":\"Integris\",\"description\":\"Global leader in Survivability Engineering & Technical Composites\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/integriscomposites.com\\\/de\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Ballistischer Schutz Nachrichten","description":"Bleiben Sie auf dem Laufenden mit Nachrichten zum ballistischen Schutz aus Europa und den Vereinigten Staaten.","canonical_url":"https:\/\/integriscomposites.com\/de\/nachrichten\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/integriscomposites.com\/de\/nachrichten\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/integriscomposites.com\/de\/#listItem","position":1,"name":"Home","item":"https:\/\/integriscomposites.com\/de\/","nextItem":{"@type":"ListItem","@id":"https:\/\/integriscomposites.com\/de\/nachrichten\/#listItem","name":"Nachrichten"}},{"@type":"ListItem","@id":"https:\/\/integriscomposites.com\/de\/nachrichten\/#listItem","position":2,"name":"Nachrichten","previousItem":{"@type":"ListItem","@id":"https:\/\/integriscomposites.com\/de\/#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/integriscomposites.com\/de\/#organization","name":"Integris","description":"Global leader in Survivability Engineering & Technical Composites","url":"https:\/\/integriscomposites.com\/de\/"},{"@type":"WebPage","@id":"https:\/\/integriscomposites.com\/de\/nachrichten\/#webpage","url":"https:\/\/integriscomposites.com\/de\/nachrichten\/","name":"Ballistischer Schutz Nachrichten","description":"Bleiben Sie auf dem Laufenden mit Nachrichten zum ballistischen Schutz aus Europa und den Vereinigten Staaten.","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/integriscomposites.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/integriscomposites.com\/de\/nachrichten\/#breadcrumblist"},"datePublished":"2024-07-16T12:26:51+00:00","dateModified":"2024-08-07T11:39:52+00:00"},{"@type":"WebSite","@id":"https:\/\/integriscomposites.com\/de\/#website","url":"https:\/\/integriscomposites.com\/de\/","name":"Integris","description":"Global leader in Survivability Engineering & Technical Composites","inLanguage":"de-DE","publisher":{"@id":"https:\/\/integriscomposites.com\/de\/#organization"}}]},"og:locale":"de_DE","og:site_name":"Integris - Global leader in Survivability Engineering &amp; Technical Composites","og:type":"article","og:title":"Ballistischer Schutz Nachrichten","og:description":"Bleiben Sie auf dem Laufenden mit Nachrichten zum ballistischen Schutz aus Europa und den Vereinigten Staaten.","og:url":"https:\/\/integriscomposites.com\/de\/nachrichten\/","article:published_time":"2024-07-16T12:26:51+00:00","article:modified_time":"2024-08-07T11:39:52+00:00","twitter:card":"summary_large_image","twitter:title":"Ballistischer Schutz Nachrichten","twitter:description":"Bleiben Sie auf dem Laufenden mit Nachrichten zum ballistischen Schutz aus Europa und den Vereinigten Staaten."},"aioseo_meta_data":{"post_id":"3201","title":"Ballistischer Schutz Nachrichten","description":"Bleiben Sie auf dem Laufenden mit Nachrichten zum ballistischen Schutz aus Europa und den Vereinigten Staaten.","keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-08-07 11:39:53","updated":"2025-06-04 22:09:11","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/integriscomposites.com\/de\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tNachrichten\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/integriscomposites.com\/de\/"},{"label":"Nachrichten","link":"https:\/\/integriscomposites.com\/de\/nachrichten\/"}],"_links":{"self":[{"href":"https:\/\/integriscomposites.com\/de\/wp-json\/wp\/v2\/pages\/3201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/integriscomposites.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/integriscomposites.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/integriscomposites.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/integriscomposites.com\/de\/wp-json\/wp\/v2\/comments?post=3201"}],"version-history":[{"count":2,"href":"https:\/\/integriscomposites.com\/de\/wp-json\/wp\/v2\/pages\/3201\/revisions"}],"predecessor-version":[{"id":3203,"href":"https:\/\/integriscomposites.com\/de\/wp-json\/wp\/v2\/pages\/3201\/revisions\/3203"}],"wp:attachment":[{"href":"https:\/\/integriscomposites.com\/de\/wp-json\/wp\/v2\/media?parent=3201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}